{"id":2060,"count":1,"description":"","link":"https:\/\/avantcore.de\/en\/day\/jakobsweg\/","name":"Jakobsweg","slug":"jakobsweg","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/tags\/2060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/posts?tags=2060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}