{"id":6956,"date":"2014-05-23T12:39:30","date_gmt":"2014-05-23T10:39:30","guid":{"rendered":"\/?p=6956"},"modified":"2025-10-10T14:55:19","modified_gmt":"2025-10-10T12:55:19","slug":"keine-erotischen-andenken","status":"publish","type":"post","link":"https:\/\/avantcore.de\/en\/keine-erotischen-andenken\/","title":{"rendered":"No erotic souvenirs"},"content":{"rendered":"<p><strong>Grunds\u00e4tzlich darf ein ehemaliger Partner auch nach Beendigung der Beziehung Fotos oder Filme des anderen, die w\u00e4hrend der Beziehung aufgenommen wurden, behalten. Aber gilt das auch f\u00fcr erotische und intime Aufnahmen? Hier\u00fcber hat nun das Oberlandesgericht Koblenz entschieden.<!--more--><\/strong><\/p>\n<p><a href=\"https:\/\/avantcore.de\/wp-content\/uploads\/2025\/01\/rrw.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/avantcore.de\/wp-content\/uploads\/2025\/01\/rrw.png\" width=\"293\" height=\"275\" \/><\/a>Nach Beendigung ihrer Beziehung kam es zwischen den Ex-Partnern u.a. zum Streit \u00fcber die Verwendung von zahlreichen Bild- und Filmaufnahmen, darunter auch intime Aufnahmen, die w\u00e4hrend der Beziehung von \u201eihr\u201c gefertigt und \u201eihm\u201c in digitalisierter Form \u00fcberlassen worden waren. Nachdem der Mann sich bereits verpflichtet hatte, es zu unterlassen, die Aufnahmen Dritten oder der \u00d6ffentlichkeit zug\u00e4nglich zu machen, ging es in dem Rechtsstreit noch darum, ob und in welchem Umfang \u00fcberlassene Dateien mit eigenen Foto- und Videoaufnahmen auch zu l\u00f6schen sind.<\/p>\n<p>Bereits das Landgericht Koblenz hatte den Mann dazu verurteilt, die in seinem Besitz befindlichen elektronischen Vervielf\u00e4ltigungsst\u00fccke von intimen Aufnahmen seiner Ex-Freundin vollst\u00e4ndig zu l\u00f6schen. Soweit die Frau dar\u00fcber hinaus auch die vollst\u00e4ndige L\u00f6schung jeglicher sie zeigender Aufnahmen beansprucht hatte, war die Klage vom Landgericht abgewiesen worden. Beide Ex-Partner legten gegen dieses Urteil des Landgerichts Berufung ein.<\/p>\n<p><b>Decision of the court<\/b><\/p>\n<p>With <a title=\"OLG Koblenz Urteil vom 20.05.2014\" href=\"http:\/\/www3.mjv.rlp.de\/rechtspr\/DisplayUrteil_neu.asp?rowguid={120F3614-5F89-422F-92CB-AE0D6E695023}\" target=\"_blank\" rel=\"noopener\">Urteil vom 20.05.2014 \u2013 Az. 3 U 1288\/13 <\/a>best\u00e4tigte das OLG Koblenz die vorangegangene landgerichtliche Entscheidung vollumf\u00e4nglich.<\/p>\n<p>Das Gericht stellte fest, dass die Frau zwar in die Erstellung und Nutzung der Lichtbilder eingewilligt habe. Soweit es sich aber um intime Aufnahmen handele, sei die Einwilligung zeitlich auf die Dauer der zwischen den Parteien bestehenden Beziehung beschr\u00e4nkt worden.<\/p>\n<p>Die Einwilligung k\u00f6nne also widerrufen werden, wenn aufgrund ver\u00e4nderter Umst\u00e4nde dem allgemeinen Pers\u00f6nlichkeitsrecht der Betroffenen Vorrang vor dem Umstand zu gew\u00e4hren ist, dass sie der Anfertigung der Aufnahmen zu irgendeinem Zeitpunkt zugestimmt hat. Das sei \u2013 so das OLG weiter \u2013 nach Beendigung der Beziehung der Fall, wenn es sich um intime und damit den Kernbereich des Pers\u00f6nlichkeitsrechts betreffende Aufnahmen handelt.<\/p>\n<p>Das den Kernbereich des Pers\u00f6nlichkeitsrechts betreffende Interesse der Frau an der L\u00f6schung der Aufnahmen sei in diesem Fall h\u00f6her zu bewerten, als das Eigentumsrecht des Mannes an der Existenz der Aufnahmen.<\/p>\n<p>Der Anspruch auf L\u00f6schung digitaler Fotografien und Videoaufnahmen ist jedoch nach Ansicht des OLG Koblenz auf diesen Bereich beschr\u00e4nkt. Denn anders als bei intimen Aufnahmen seien Lichtbilder, welche die Frau im bekleideten Zustand in Alltags- oder Urlaubssituationen zeigten, in einem geringeren Ma\u00dfe geeignet, ihr Ansehen gegen\u00fcber Dritten zu beeintr\u00e4chtigen. Es sei allgemein \u00fcblich, dass Personen, denen die Fertigung von Aufnahmen bei Feiern, Festen und im Urlaub gestattet werde, diese auf Dauer besitzen und nutzen d\u00fcrfen. Hinsichtlich derartiger Aufnahmen bestehe daher gegen den Ex-Partner kein Anspruch auf L\u00f6schung.<\/p>\n<p><b>Conclusion<\/b><\/p>\n<p>Es bleibt zun\u00e4chst abzuwarten, ob das Urteil rechtkr\u00e4ftig wird und sich ggf. auch andere Gerichte der hier ge\u00e4u\u00dferten Auffassung des OLG Koblenz anschlie\u00dfen. Unabh\u00e4ngig davon sollte man stets abw\u00e4gen, zu welchen Aufnahmen man seine Einwilligung erteilt und wem man diese dann zur Verf\u00fcgung stellt.<\/p>","protected":false},"excerpt":{"rendered":"<p>Grunds\u00e4tzlich darf ein ehemaliger Partner auch nach Beendigung der Beziehung Fotos oder Filme des anderen, die w\u00e4hrend der Beziehung aufgenommen wurden, behalten. Aber gilt das auch f\u00fcr erotische und intime Aufnahmen? Hier\u00fcber hat nun das Oberlandesgericht Koblenz entschieden.<\/p>","protected":false},"author":2,"featured_media":24106,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"single-custom-blog.php","format":"standard","meta":{"footnotes":""},"categories":[3049],"tags":[101,295,320,2342,2343,2344,2643,104],"ppma_author":[3074],"class_list":["post-6956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-allgemeines-persoenlichkeitsrecht","tag-foto","tag-loeschung-von-daten","tag-nacktbild","tag-nacktbilder","tag-nacktfoto","tag-nacktotos","tag-persoenlichkeitsrecht"],"authors":[{"term_id":3074,"user_id":2,"is_guest":0,"slug":"christopher","display_name":"Christopher A. Wolf, MBA","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/d77b27aefd4397c799a733f749d595a8fcc78bb7c7d693f68096bc2bfc958647?s=96&d=mm&r=g","first_name":"Christopher A.","last_name":"Wolf, MBA","user_url":"","description":""}],"_links":{"self":[{"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/posts\/6956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/comments?post=6956"}],"version-history":[{"count":0,"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/posts\/6956\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/media\/24106"}],"wp:attachment":[{"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/media?parent=6956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/categories?post=6956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/tags?post=6956"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/ppma_author?post=6956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}