{"id":13683,"date":"2017-07-27T09:48:04","date_gmt":"2017-07-27T07:48:04","guid":{"rendered":"https:\/\/www.kpw-law.de\/?p=13683\/"},"modified":"2025-10-08T13:53:27","modified_gmt":"2025-10-08T11:53:27","slug":"verstoss-gegen-unterlassungserklaerung-mit-kundenbewertung-auf-der-webseite","status":"publish","type":"post","link":"https:\/\/avantcore.de\/en\/verstoss-gegen-unterlassungserklaerung-mit-kundenbewertung-auf-der-webseite\/","title":{"rendered":"Versto\u00df gegen Unterlassungserkl\u00e4rung mit Kundenbewertungen auf Webseite"},"content":{"rendered":"<p><strong>Gibt man auf eine Abmahnung eine strafbewehrte Unterlassungserkl\u00e4rung ab, so drohen bei Verst\u00f6\u00dfen gegen die Unterlassungspflicht hohe Vertragsstrafen. Kommt auch dann eine Vertragsstrafe in Betracht, wenn die Unterlassungserkl\u00e4rung die Pflicht beinhaltet, mit einer bestimmten Aussage nicht mehr zu werben und Kundenbewertungen kerngleiche Aussagen treffen? Das Oberlandesgericht K\u00f6ln hatte dies zu entscheiden.<\/strong><\/p>\n<p><!--more--><\/p>\n<p>Ein Unternehmen bewarb seine &#8220;Zauberwaschkugeln&#8221; f\u00fcr Waschmaschine und Geschirrsp\u00fcler im Internet mit der Angabe &#8220;Spart Waschmittel&#8221;.<\/p>\n<p>Ein Wettbewerbsverband sah darin eine wettbewerbswidrige Irref\u00fchrung, da der Werbeaussage keine gesicherte wissenschaftliche Erkenntnis zu Grunde liege. Der Verband mahnte das werbende Unternehmen ab, woraufhin das Unternehmen eine strafbewehrte Unterlassungserkl\u00e4rung abgab. Darin verpflichtete es sich zu unterlassen, im gesch\u00e4ftlichen Verkehr f\u00fcr &#8220;Zauberwaschkugeln f\u00fcr Waschmaschine und Geschirrsp\u00fcler&#8221; wie folgt zu werben: &#8220;Spart Waschmittel&#8221;.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/avantcore.de\/wp-content\/uploads\/2025\/01\/rrw.png\" alt=\"Sun at AVANTCORE\" width=\"379\" height=\"164\" \/>Auf der Webseite des Unternehmens befanden sich auch nach der Abgabe der Unterlassungserkl\u00e4rung noch Kundenbewertungen wie beispielsweise <em>&#8220;Ich benutze weniger Waschmittel.&#8221;<\/em> or <em>&#8220;Brauchte weniger Waschmittel und die W\u00e4sche ist griffiger und nicht so hart.&#8221;.<\/em><\/p>\n<p>Der Wettbewerbsverband ist der Auffassung, das Unternehmen habe aufgrund des Nichtl\u00f6schens der Kundenbewertungen gegen die Unterlassungsverpflichtung versto\u00dfen und erhob Klage.<\/p>\n<p>Das Unternehmen dagegen ist der Ansicht, die Unterlassungsverpflichtung beschr\u00e4nke sich auf das eigene Werben und umfasse nicht die Ver\u00f6ffentlichung von Bewertungen.<\/p>\n<p>Das LG Aachen gab der Klage des Wettbewerbsverbandes statt. Das beklagte Unternehmen legte gegen das Urteil Berufung ein.<\/p>\n<h2>The court's decision<\/h2>\n<p>Die Berufung wies das OLG K\u00f6ln zur\u00fcck. Das OLG K\u00f6ln entschied mit <a href=\"https:\/\/www.justiz.nrw.de\/nrwe\/olgs\/koeln\/j2017\/6_U_161_16_Urteil_20170524.html\" target=\"_blank\" rel=\"noopener noreferrer\">Urteil vom 24.05.2017 &#8211; Az. 6 U 161\/16<\/a>, dass auch diese Kundenbewertungen unter die Unterlassungserkl\u00e4rung fallen.<\/p>\n<p>Das Gericht legte die konkrete Unterlassungserkl\u00e4rung dahingehend aus, dass auch solche Werbeaussagen umfasst sein sollten, die im Kern gleich sind und die sich im Bereich der Kundenkommentare befanden.<\/p>\n<p>Die Kundenbewertungen seien Werbung, denn das Einstellen von Kundenbewertungen diene allein dem Zweck, Vertrauen in die Leistungen des Produkts zu schaffen.<\/p>\n<p>Ferner handele es sich um ein eigenes Angebot des Unternehmens, denn es nutze die M\u00f6glichkeit der Bewertung ihres Produktes zu Werbezwecken.<\/p>\n<h2>Conclusion<\/h2>\n<p>Das OLG K\u00f6ln stellt klar, dass die in den Kundenbewertungen auf einer Unternehmenswebseite enthaltene Aussagen eine unzul\u00e4ssige Werbung darstellen k\u00f6nnen. Verpflichtet sich ein Unternehmen zur Unterlassung einer bestimmten Werbung, kann es auch zur L\u00f6schung von Kunden\u00e4u\u00dferungen auf seiner Webseite verpflichtet sein, die das Produkt ebenfalls in gleichwertiger Weise bewerben. Ob dies der Fall ist, ist im Einzelfall im Rahmen einer Auslegung der Unterlassungsvereinbarung festzustellen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Gibt man auf eine Abmahnung eine strafbewehrte Unterlassungserkl\u00e4rung ab, so drohen bei Verst\u00f6\u00dfen gegen die Unterlassungspflicht hohe Vertragsstrafen. Kommt auch dann eine Vertragsstrafe in Betracht, wenn die Unterlassungserkl\u00e4rung die Pflicht beinhaltet, mit einer bestimmten Aussage nicht mehr zu werben und Kundenbewertungen kerngleiche Aussagen treffen? Das Oberlandesgericht K\u00f6ln hatte dies zu entscheiden.<\/p>","protected":false},"author":2,"featured_media":24106,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"single-custom-blog.php","format":"standard","meta":{"footnotes":""},"categories":[3049],"tags":[2960,2682,558,316,2848,317,2961,355,411,551],"ppma_author":[3074],"class_list":["post-13683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-kundenaeusserung","tag-kundenbewertung","tag-strafbewehrte-unterlassungserklaerung","tag-unterlassungserklaerung","tag-verstoss","tag-vertragsstrafe","tag-waschmittel","tag-werbeaussage","tag-werbung","tag-wettbewerbsverband"],"authors":[{"term_id":3074,"user_id":2,"is_guest":0,"slug":"christopher","display_name":"Christopher A. Wolf, MBA","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/d77b27aefd4397c799a733f749d595a8fcc78bb7c7d693f68096bc2bfc958647?s=96&d=mm&r=g","first_name":"Christopher A.","last_name":"Wolf, MBA","user_url":"","description":""}],"_links":{"self":[{"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/posts\/13683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/comments?post=13683"}],"version-history":[{"count":0,"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/posts\/13683\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/media\/24106"}],"wp:attachment":[{"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/media?parent=13683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/categories?post=13683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/tags?post=13683"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/avantcore.de\/en\/wp-json\/wp\/v2\/ppma_author?post=13683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}